{"id":1241,"count":5,"description":"","link":"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/","name":"Sell flat Barcelona","slug":"sell-flat-barcelona","taxonomy":"category","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"vN14TVyuwbSejjrku0aTkka1RW4nVROhF4V9cpCSSt4\" \/>\n\t<meta name=\"p:domain_verify\" content=\"b1bb8b715d64c9a52340e771481bfba9\" \/>\n\t<meta name=\"yandex-verification\" content=\"7119d6f274db7d0d\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Your trusted real estate agency in Barcelona - Vende tu piso en Barcelona\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sell flat Barcelona - Your trusted real estate agency in Barcelona\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"209\" \/>\n\t\t<meta property=\"og:image:height\" content=\"57\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ArquitecturaResidencialBCN\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@ArquitecturaResidencial\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sell flat Barcelona - Your trusted real estate agency in Barcelona\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/1241\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/category\\\/sell-flat-barcelona\\\/#listItem\",\"name\":\"Sell flat Barcelona\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/category\\\/sell-flat-barcelona\\\/#listItem\",\"position\":2,\"name\":\"Sell flat Barcelona\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/1241\\\/#collectionpage\",\"url\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/1241\\\/\",\"name\":\"Sell flat Barcelona - Your trusted real estate agency in Barcelona\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/1241\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#organization\",\"name\":\"Arquitectura Residencial\",\"description\":\"Vende tu piso en Barcelona\",\"url\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/\",\"email\":\"hola@arqresidencial.com\",\"telephone\":\"+34932411103\",\"foundingDate\":\"1930-11-03\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"value\":3},\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/arqresidencial.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo_AR_col_153965.svg\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/1241\\\/#organizationLogo\",\"width\":209,\"height\":57,\"caption\":\"Logotipo azul de Arquitectura Residencial\"},\"image\":{\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/wp-json\\\/wp\\\/v2\\\/categories\\\/1241\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ArquitecturaResidencialBCN\\\/\",\"https:\\\/\\\/twitter.com\\\/ArquitecturaResidencial\",\"https:\\\/\\\/www.instagram.com\\\/arquitectura_residencial\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/ArquitecturaResidencialBCN\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/arquitectura-residencial-residencial-pineda-park-sl\\\/?viewAsMember=true\"],\"address\":{\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#postaladdress\",\"@type\":\"PostalAddress\",\"streetAddress\":\"Freixa, 26-28, Bajos 3\",\"postalCode\":\"08021\",\"addressLocality\":\"Barcelona\",\"addressRegion\":\"Barcelona\",\"addressCountry\":\"ES\"},\"vatID\":\"B60373214\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/\",\"name\":\"Arquitectura Residencial\",\"alternateName\":\"arqresidencial\",\"description\":\"Vende tu piso en Barcelona\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/arqresidencial.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Sell flat Barcelona - Your trusted real estate agency in Barcelona<\/title>\n\n","aioseo_head_json":{"title":"Sell flat Barcelona - Your trusted real estate agency in Barcelona","description":"","canonical_url":"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"vN14TVyuwbSejjrku0aTkka1RW4nVROhF4V9cpCSSt4","p:domain_verify":"b1bb8b715d64c9a52340e771481bfba9","yandex-verification":"7119d6f274db7d0d","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/arqresidencial.com\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/arqresidencial.com\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/#listItem","name":"Sell flat Barcelona"}},{"@type":"ListItem","@id":"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/#listItem","position":2,"name":"Sell flat Barcelona","previousItem":{"@type":"ListItem","@id":"https:\/\/arqresidencial.com\/en\/#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241\/#collectionpage","url":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241\/","name":"Sell flat Barcelona - Your trusted real estate agency in Barcelona","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/arqresidencial.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/arqresidencial.com\/en\/#organization","name":"Arquitectura Residencial","description":"Vende tu piso en Barcelona","url":"https:\/\/arqresidencial.com\/en\/","email":"hola@arqresidencial.com","telephone":"+34932411103","foundingDate":"1930-11-03","numberOfEmployees":{"@type":"QuantitativeValue","value":3},"logo":{"@type":"ImageObject","url":"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg","@id":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241\/#organizationLogo","width":209,"height":57,"caption":"Logotipo azul de Arquitectura Residencial"},"image":{"@id":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/ArquitecturaResidencialBCN\/","https:\/\/twitter.com\/ArquitecturaResidencial","https:\/\/www.instagram.com\/arquitectura_residencial\/","https:\/\/www.pinterest.es\/ArquitecturaResidencialBCN\/","https:\/\/www.linkedin.com\/company\/arquitectura-residencial-residencial-pineda-park-sl\/?viewAsMember=true"],"address":{"@id":"https:\/\/arqresidencial.com\/en\/#postaladdress","@type":"PostalAddress","streetAddress":"Freixa, 26-28, Bajos 3","postalCode":"08021","addressLocality":"Barcelona","addressRegion":"Barcelona","addressCountry":"ES"},"vatID":"B60373214"},{"@type":"WebSite","@id":"https:\/\/arqresidencial.com\/en\/#website","url":"https:\/\/arqresidencial.com\/en\/","name":"Arquitectura Residencial","alternateName":"arqresidencial","description":"Vende tu piso en Barcelona","inLanguage":"en-US","publisher":{"@id":"https:\/\/arqresidencial.com\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Your trusted real estate agency in Barcelona - Vende tu piso en Barcelona","og:type":"article","og:title":"Sell flat Barcelona - Your trusted real estate agency in Barcelona","og:url":"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/","og:image":"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg","og:image:secure_url":"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg","og:image:width":209,"og:image:height":57,"article:publisher":"https:\/\/www.facebook.com\/ArquitecturaResidencialBCN\/","twitter:card":"summary_large_image","twitter:site":"@ArquitecturaResidencial","twitter:title":"Sell flat Barcelona - Your trusted real estate agency in Barcelona","twitter:image":"https:\/\/arqresidencial.com\/wp-content\/uploads\/2023\/05\/logo_AR_col_153965.svg"},"aioseo_meta_data":{"term_id":"1241","title":null,"description":null,"keywords":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_custom_url":null,"og_image_custom_fields":null,"og_custom_image_width":null,"og_custom_image_height":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","tabs":null,"local_seo":null,"seo_analyzer_scan_date":"2026-04-28 21:21:29","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"breadcrumb_settings":null,"created":"2026-03-26 19:36:20","updated":"2026-04-28 21:21:29","og_image_url":null,"og_image_width":null,"og_image_height":null,"twitter_image_url":null,"pillar_content":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/arqresidencial.com\/en\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\tSell flat Barcelona\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/arqresidencial.com\/en\/"},{"label":"Sell flat Barcelona","link":"https:\/\/arqresidencial.com\/en\/category\/sell-flat-barcelona\/"}],"_links":{"self":[{"href":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories\/1241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/arqresidencial.com\/en\/wp-json\/wp\/v2\/posts?categories=1241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}